{"id":3451,"date":"2024-11-08T11:43:39","date_gmt":"2024-11-08T10:43:39","guid":{"rendered":"https:\/\/www.laicatosaveriano.it\/?p=3451"},"modified":"2024-11-08T11:44:08","modified_gmt":"2024-11-08T10:44:08","slug":"laccoglienza-della-famiglia-calo","status":"publish","type":"post","link":"https:\/\/www.laicatosaveriano.it\/en\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html","title":{"rendered":"(Italiano) L\u2019accoglienza della famiglia Cal\u00f2"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.laicatosaveriano.it\/it\/wp-json\/wp\/v2\/posts\/3451\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":2,"featured_media":3453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,1,82],"tags":[],"class_list":["post-3451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-animazione-missionaria","category-generale","category-iniziative"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]L\u2019accoglienza della famiglia Cal\u00f2[:] - Laicato Saveriano\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\" \/>\n<meta property=\"og:site_name\" content=\"Laicato Saveriano\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T10:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T10:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"589\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\"},\"author\":{\"name\":\"Redazione Web\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/01dd8a7af7ad569736008241f4939b94\"},\"headline\":\"(Italiano) L\u2019accoglienza della famiglia Cal\u00f2\",\"datePublished\":\"2024-11-08T10:43:39+00:00\",\"dateModified\":\"2024-11-08T10:44:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\"},\"wordCount\":1408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg\",\"articleSection\":[\"Animazione missionaria\",\"Senza categoria\",\"\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\",\"url\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\",\"name\":\"[:it]L\u2019accoglienza della famiglia Cal\u00f2[:] - Laicato Saveriano\",\"isPartOf\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg\",\"datePublished\":\"2024-11-08T10:43:39+00:00\",\"dateModified\":\"2024-11-08T10:44:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage\",\"url\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg\",\"contentUrl\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg\",\"width\":589,\"height\":278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.laicatosaveriano.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019accoglienza della famiglia Cal\u00f2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#website\",\"url\":\"https:\/\/www.laicatosaveriano.it\/\",\"name\":\"Laicato Saveriano\",\"description\":\"Fare del mondo una sola famiglia\",\"publisher\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laicatosaveriano.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#organization\",\"name\":\"Laicato Saveriano\",\"url\":\"https:\/\/www.laicatosaveriano.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2024\/11\/cropped-logocropped-logo-laicato-saveriano.jpg\",\"contentUrl\":\"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2024\/11\/cropped-logocropped-logo-laicato-saveriano.jpg\",\"width\":511,\"height\":511,\"caption\":\"Laicato Saveriano\"},\"image\":{\"@id\":\"https:\/\/www.laicatosaveriano.it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/01dd8a7af7ad569736008241f4939b94\",\"name\":\"Redazione Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ba304e3e1f74405110024b2eaa65f43333c9ec10e72b68e2ca6ac3001d6faed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ba304e3e1f74405110024b2eaa65f43333c9ec10e72b68e2ca6ac3001d6faed?s=96&d=mm&r=g\",\"caption\":\"Redazione Web\"},\"url\":\"https:\/\/www.laicatosaveriano.it\/en\/author\/redazione\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]L\u2019accoglienza della famiglia Cal\u00f2[:] - Laicato Saveriano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html","og_locale":"en_US","og_type":"article","og_title":"[:it]L\u2019accoglienza della famiglia Cal\u00f2[:] - Laicato Saveriano","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html","og_site_name":"Laicato Saveriano","article_published_time":"2024-11-08T10:43:39+00:00","article_modified_time":"2024-11-08T10:44:08+00:00","og_image":[{"width":589,"height":278,"url":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg","type":"image\/jpeg"}],"author":"Redazione Web","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione Web","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#article","isPartOf":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html"},"author":{"name":"Redazione Web","@id":"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/01dd8a7af7ad569736008241f4939b94"},"headline":"(Italiano) L\u2019accoglienza della famiglia Cal\u00f2","datePublished":"2024-11-08T10:43:39+00:00","dateModified":"2024-11-08T10:44:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html"},"wordCount":1408,"commentCount":0,"publisher":{"@id":"https:\/\/www.laicatosaveriano.it\/#organization"},"image":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage"},"thumbnailUrl":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg","articleSection":["Animazione missionaria","Senza categoria",""],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html","url":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html","name":"[:it]L\u2019accoglienza della famiglia Cal\u00f2[:] - Laicato Saveriano","isPartOf":{"@id":"https:\/\/www.laicatosaveriano.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage"},"image":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage"},"thumbnailUrl":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg","datePublished":"2024-11-08T10:43:39+00:00","dateModified":"2024-11-08T10:44:08+00:00","breadcrumb":{"@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#primaryimage","url":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg","contentUrl":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2019\/06\/Cattura-3.jpg","width":589,"height":278},{"@type":"BreadcrumbList","@id":"https:\/\/www.laicatosaveriano.it\/2024\/11\/08\/laccoglienza-della-famiglia-calo.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.laicatosaveriano.it\/"},{"@type":"ListItem","position":2,"name":"L\u2019accoglienza della famiglia Cal\u00f2"}]},{"@type":"WebSite","@id":"https:\/\/www.laicatosaveriano.it\/#website","url":"https:\/\/www.laicatosaveriano.it\/","name":"Laicato Saveriano","description":"Fare del mondo una sola famiglia","publisher":{"@id":"https:\/\/www.laicatosaveriano.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laicatosaveriano.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.laicatosaveriano.it\/#organization","name":"Laicato Saveriano","url":"https:\/\/www.laicatosaveriano.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laicatosaveriano.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2024\/11\/cropped-logocropped-logo-laicato-saveriano.jpg","contentUrl":"https:\/\/www.laicatosaveriano.it\/wp-content\/uploads\/2024\/11\/cropped-logocropped-logo-laicato-saveriano.jpg","width":511,"height":511,"caption":"Laicato Saveriano"},"image":{"@id":"https:\/\/www.laicatosaveriano.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/01dd8a7af7ad569736008241f4939b94","name":"Redazione Web","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laicatosaveriano.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ba304e3e1f74405110024b2eaa65f43333c9ec10e72b68e2ca6ac3001d6faed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ba304e3e1f74405110024b2eaa65f43333c9ec10e72b68e2ca6ac3001d6faed?s=96&d=mm&r=g","caption":"Redazione Web"},"url":"https:\/\/www.laicatosaveriano.it\/en\/author\/redazione"}]}},"_links":{"self":[{"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/posts\/3451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/comments?post=3451"}],"version-history":[{"count":0,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/posts\/3451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/media\/3453"}],"wp:attachment":[{"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/media?parent=3451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/categories?post=3451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laicatosaveriano.it\/en\/wp-json\/wp\/v2\/tags?post=3451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}